{"id":142453,"date":"2025-04-01T11:23:05","date_gmt":"2025-04-01T09:23:05","guid":{"rendered":"https:\/\/coin24.ee\/product\/1-dollar-ssha-2025-korennye-narody-ssha-meri-kavena-pukui\/"},"modified":"2025-04-03T20:50:53","modified_gmt":"2025-04-03T18:50:53","slug":"1-dollar-ssha-2025-korennye-narody-ssha-meri-kavena-pukui","status":"publish","type":"product","link":"https:\/\/coin24.ee\/es\/producto\/1-dollar-ssha-2025-korennye-narody-ssha-meri-kavena-pukui\/","title":{"rendered":"1 d\u00f3lar estadounidense 2025 Pueblos Ind\u00edgenas de Estados Unidos &#8211; Mary Kawena Pukui"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Como parte de la Serie de los Pueblos Nativos, se ha emitido una moneda conmemorativa de 1 $ en honor de Mary Kawena Pukui, destacada escritora, investigadora y experta en la cultura hawaiana. La moneda tambi\u00e9n rinde homenaje a su obra N\u0101n\u0101 i ke Kumu (Mira a la Fuente), una de las m\u00e1s significativas sobre las tradiciones y valores hawaianos.<\/p>\n<p>Mary Kawena Pukui ha desempe\u00f1ado un papel clave en la conservaci\u00f3n de la lengua hawaiana, las historias orales y el patrimonio cultural. Es autora y coautora de m\u00e1s de 50 libros y 150 art\u00edculos, incluidos diccionarios, estudios etnogr\u00e1ficos y colecciones de proverbios. Su trabajo ha ayudado a reconectar a muchos hawaianos con sus ra\u00edces, poniendo a disposici\u00f3n de las generaciones futuras unos conocimientos inestimables.<\/p>\n<p>El reverso de la moneda muestra un retrato de Mary Kawena Pukui, junto al que aparecen p\u00e1ginas del libro N\u0101n\u0101 i ke Kumu y motivos tradicionales hawaianos que simbolizan la profunda conexi\u00f3n de la naci\u00f3n con su historia. El dise\u00f1o tambi\u00e9n incluye la imagen de un kumu (maestro) transmitiendo conocimientos a un alumno, lo que refleja la idea central de su libro: una apelaci\u00f3n a la sabidur\u00eda de los antepasados.<\/p>\n<p>Esta moneda no s\u00f3lo celebra la contribuci\u00f3n de Mary Kawena Pukui al estudio y la conservaci\u00f3n de la cultura hawaiana, sino que tambi\u00e9n subraya la importancia de la tradici\u00f3n, el conocimiento y su transmisi\u00f3n a las generaciones futuras.<\/p>\n<p>Serie: Pueblos Ind\u00edgenas de los EE.UU.<br \/>\nValor nominal: 1 USD<br \/>\nPeso: 8,1g<br \/>\nDi\u00e1metro: 26,5 mm<\/p>\n","protected":false},"featured_media":142428,"template":"","meta":[],"product_brand":[],"product_cat":[4271,4281],"product_tag":[],"giftcard-category":[],"class_list":["post-142453","product","type-product","status-publish","has-post-thumbnail","product_cat-coleccionable","product_cat-dolar-america","pa_country-ameerika-uhendriigid-es-2","pa_quality-mark-unc-es","pa_year1-2025-es","first","instock","featured","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/product\/142453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/product\/142453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/media\/142428"}],"wp:attachment":[{"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/media?parent=142453"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/product_brand?post=142453"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/product_cat?post=142453"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/product_tag?post=142453"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/coin24.ee\/es\/wp-json\/wp\/v2\/giftcard-category?post=142453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}